{"id":2018,"date":"2022-03-21T14:52:45","date_gmt":"2022-03-21T13:52:45","guid":{"rendered":"https:\/\/www.molinoborgioli.it\/?post_type=inostrigrani&#038;p=2018"},"modified":"2022-07-29T11:30:25","modified_gmt":"2022-07-29T09:30:25","slug":"la-rotazione-colturale-per-cibo-sostenibile-e-sicuro","status":"publish","type":"inostrigrani","link":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/","title":{"rendered":"La rotazione colturale per cibo sostenibile e sicuro"},"content":{"rendered":"<div class=\"gb-container gb-container-d47ac280\"><div class=\"gb-inside-container\">\n\n<p>La rotazione colturale \u00e8 una tecnica utilizzata in agricoltura che prevede l\u2019alternanza di diverse colture sullo stesso terreno, con l\u2019obiettivo di riequilibrare le propriet\u00e0 biologiche, chimiche e fisiche del suolo coltivato.<\/p>\n\n\n\n<p>Il frumento, come tutti i cereali da granella, \u00e8 una coltura che per la propria crescita necessita degli elementi nutritivi presenti nel terreno e lo impoverisce. \u00c8 quindi necessario alternarlo con colture da rinnovo e colture miglioratrici (principalmente le leguminose) che sono in grado di fissare l\u2019azoto atmosferico e aumentare la fertilit\u00e0 del terreno, arricchendolo di elementi nutritivi.<\/p>\n\n\n\n<p>L\u2019avvicendamento \u00e8 sempre stato praticato prima dell\u2019avvento della meccanizzazione, ma successivamente ci si \u00e8 orientati verso un\u2019agricoltura intensiva, ricorrendo a fertilizzanti e pesticidi, che possono avere effetti nocivi sull\u2019ambiente e sulla salubrit\u00e0 dei prodotti alimentari se impiegati in eccesso. I nostri agricoltori sono consapevoli di svolgere un ruolo chiave sia per garantire ogni giorno cibo <strong>sostenibile e sicuro<\/strong>, sia per preservare i <strong>nostri<\/strong> <strong>territori<\/strong> e risorse. Per questo motivo, applicano la rotazione colturale per evitare lo sfruttamento del suolo e mantenerlo naturalmente fertile.<\/p>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2019,"parent":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"inostrigrani-category":[130,27],"class_list":["post-2018","inostrigrani","type-inostrigrani","status-publish","has-post-thumbnail","hentry","inostrigrani-category-le-naturali-contaminazioni","inostrigrani-category-rotazione-colturale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La rotazione colturale per cibo sostenibile e sicuro - Naturalmente Molino Borgioli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La rotazione colturale per cibo sostenibile e sicuro - Naturalmente Molino Borgioli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Naturalmente Molino Borgioli\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-29T09:30:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2022\/03\/rotazione-nmb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/\",\"url\":\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/\",\"name\":\"La rotazione colturale per cibo sostenibile e sicuro - Naturalmente Molino Borgioli\",\"isPartOf\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2022\/03\/rotazione-nmb.jpg\",\"datePublished\":\"2022-03-21T13:52:45+00:00\",\"dateModified\":\"2022-07-29T09:30:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/#primaryimage\",\"url\":\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2022\/03\/rotazione-nmb.jpg\",\"contentUrl\":\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2022\/03\/rotazione-nmb.jpg\",\"width\":2160,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.molinoborgioli.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I nostri Grani\",\"item\":\"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La rotazione colturale per cibo sostenibile e sicuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#website\",\"url\":\"https:\/\/www.molinoborgioli.it\/en\/\",\"name\":\"Naturalmente Molino Borgioli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.molinoborgioli.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#organization\",\"name\":\"Naturalmente Molino Borgioli\",\"url\":\"https:\/\/www.molinoborgioli.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/cropped-cropped-cropped-logo-borgioli-2-1-110x66-1.png\",\"contentUrl\":\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/cropped-cropped-cropped-logo-borgioli-2-1-110x66-1.png\",\"width\":110,\"height\":66,\"caption\":\"Naturalmente Molino Borgioli\"},\"image\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La rotazione colturale per cibo sostenibile e sicuro - Naturalmente Molino Borgioli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/","og_locale":"en_US","og_type":"article","og_title":"La rotazione colturale per cibo sostenibile e sicuro - Naturalmente Molino Borgioli","og_url":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/","og_site_name":"Naturalmente Molino Borgioli","article_modified_time":"2022-07-29T09:30:25+00:00","og_image":[{"width":2160,"height":1440,"url":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2022\/03\/rotazione-nmb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/","url":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/","name":"La rotazione colturale per cibo sostenibile e sicuro - Naturalmente Molino Borgioli","isPartOf":{"@id":"https:\/\/www.molinoborgioli.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/#primaryimage"},"image":{"@id":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2022\/03\/rotazione-nmb.jpg","datePublished":"2022-03-21T13:52:45+00:00","dateModified":"2022-07-29T09:30:25+00:00","breadcrumb":{"@id":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/#primaryimage","url":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2022\/03\/rotazione-nmb.jpg","contentUrl":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2022\/03\/rotazione-nmb.jpg","width":2160,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/la-rotazione-colturale-per-cibo-sostenibile-e-sicuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.molinoborgioli.it\/en\/"},{"@type":"ListItem","position":2,"name":"I nostri Grani","item":"https:\/\/www.molinoborgioli.it\/en\/inostrigrani\/"},{"@type":"ListItem","position":3,"name":"La rotazione colturale per cibo sostenibile e sicuro"}]},{"@type":"WebSite","@id":"https:\/\/www.molinoborgioli.it\/en\/#website","url":"https:\/\/www.molinoborgioli.it\/en\/","name":"Naturalmente Molino Borgioli","description":"","publisher":{"@id":"https:\/\/www.molinoborgioli.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.molinoborgioli.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.molinoborgioli.it\/en\/#organization","name":"Naturalmente Molino Borgioli","url":"https:\/\/www.molinoborgioli.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.molinoborgioli.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/cropped-cropped-cropped-logo-borgioli-2-1-110x66-1.png","contentUrl":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/cropped-cropped-cropped-logo-borgioli-2-1-110x66-1.png","width":110,"height":66,"caption":"Naturalmente Molino Borgioli"},"image":{"@id":"https:\/\/www.molinoborgioli.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/inostrigrani\/2018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/inostrigrani"}],"about":[{"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/types\/inostrigrani"}],"author":[{"embeddable":true,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/comments?post=2018"}],"version-history":[{"count":0,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/inostrigrani\/2018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/media\/2019"}],"wp:attachment":[{"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/media?parent=2018"}],"wp:term":[{"taxonomy":"inostrigrani-category","embeddable":true,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/inostrigrani-category?post=2018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}