{"id":612,"date":"2021-03-30T18:17:10","date_gmt":"2021-03-30T16:17:10","guid":{"rendered":"https:\/\/www.molinoborgioli.it\/mb\/?post_type=ricette&#038;p=612"},"modified":"2021-09-01T12:19:12","modified_gmt":"2021-09-01T10:19:12","slug":"pappardelle-alluovo","status":"publish","type":"ricette","link":"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/","title":{"rendered":"Pappardelle all&#8217;uovo"},"content":{"rendered":"<div class=\"gb-grid-wrapper gb-grid-wrapper-39d84e83\">\n<div class=\"gb-grid-column gb-grid-column-e1a13380\"><div class=\"gb-container gb-container-e1a13380\"><div class=\"gb-inside-container\">\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"PAPPARDELLE ALL&#039;UOVO - ricetta facile MOLINO BORGIOLI\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/kKU74sq-LKg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong><em>Ingredienti per 4 persone<br>Semola Fine <strong>di grano toscano<\/strong><\/em><\/strong> <strong><em>Molino Borgioli &#8211; 170 g<\/em><\/strong><br>Uova &#8211; 3<br>Sale &#8211; 1 pizzico<br>Olio &#8211; 1 cucchiaino<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong><em>Preparazione<\/em><\/strong><br>Versare la Semola Fine Molino Borgioli sul piano di lavoro e formare la fontana in cui aggiungere l\u2019uovo, il sale e l\u2019olio. Lavorare l\u2019impasto, prima con la forchetta, poi con le mani. Formare un panetto e coprirlo con pellicola trasparente lasciandolo riposare per almeno 30 minuti.<br>Stendere l\u2019impasto con il mattarello su una spianatoia infarinata, coprire con un canovaccio e lasciare riposare per 30 minuti.<br>Arrotolate la pasta da ambedue le parti. Tagliare a striscioline in modo da formare le pappardelle. Conditele a vostra scelta, buon appetito!<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1743,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"ricette-category":[7],"prodotto-category":[15],"class_list":["post-612","ricette","type-ricette","status-publish","has-post-thumbnail","hentry","ricette-category-pasta","prodotto-category-semola-fine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pappardelle all&#039;uovo - Ricetta Naturalmente Molino Borgioli - Pasta<\/title>\n<meta name=\"description\" content=\"Pappardelle all&#039;uovo una gustosa ricetta Naturalmente Molino Borgioli fatta con Semola fine\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pappardelle all&#039;uovo - Ricetta Naturalmente Molino Borgioli - Pasta\" \/>\n<meta property=\"og:description\" content=\"Pappardelle all&#039;uovo una gustosa ricetta Naturalmente Molino Borgioli fatta con Semola fine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/\" \/>\n<meta property=\"og:site_name\" content=\"Naturalmente Molino Borgioli\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T10:19:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/pappardelle-molinoborgioli-video.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1087\" \/>\n\t<meta property=\"og:image:height\" content=\"1087\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/\",\"url\":\"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/\",\"name\":\"Pappardelle all'uovo - Ricetta Naturalmente Molino Borgioli - Pasta\",\"isPartOf\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/pappardelle-molinoborgioli-video.jpg\",\"datePublished\":\"2021-03-30T16:17:10+00:00\",\"dateModified\":\"2021-09-01T10:19:12+00:00\",\"description\":\"Pappardelle all'uovo una gustosa ricetta Naturalmente Molino Borgioli fatta con Semola fine\",\"breadcrumb\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/#primaryimage\",\"url\":\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/pappardelle-molinoborgioli-video.jpg\",\"contentUrl\":\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/pappardelle-molinoborgioli-video.jpg\",\"width\":1087,\"height\":1087},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.molinoborgioli.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricette\",\"item\":\"https:\/\/www.molinoborgioli.it\/en\/ricette\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pappardelle all&#8217;uovo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#website\",\"url\":\"https:\/\/www.molinoborgioli.it\/en\/\",\"name\":\"Naturalmente Molino Borgioli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.molinoborgioli.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#organization\",\"name\":\"Naturalmente Molino Borgioli\",\"url\":\"https:\/\/www.molinoborgioli.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/cropped-cropped-cropped-logo-borgioli-2-1-110x66-1.png\",\"contentUrl\":\"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/cropped-cropped-cropped-logo-borgioli-2-1-110x66-1.png\",\"width\":110,\"height\":66,\"caption\":\"Naturalmente Molino Borgioli\"},\"image\":{\"@id\":\"https:\/\/www.molinoborgioli.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pappardelle all'uovo - Ricetta Naturalmente Molino Borgioli - Pasta","description":"Pappardelle all'uovo una gustosa ricetta Naturalmente Molino Borgioli fatta con Semola fine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/","og_locale":"en_US","og_type":"article","og_title":"Pappardelle all'uovo - Ricetta Naturalmente Molino Borgioli - Pasta","og_description":"Pappardelle all'uovo una gustosa ricetta Naturalmente Molino Borgioli fatta con Semola fine","og_url":"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/","og_site_name":"Naturalmente Molino Borgioli","article_modified_time":"2021-09-01T10:19:12+00:00","og_image":[{"width":1087,"height":1087,"url":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/pappardelle-molinoborgioli-video.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/","url":"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/","name":"Pappardelle all'uovo - Ricetta Naturalmente Molino Borgioli - Pasta","isPartOf":{"@id":"https:\/\/www.molinoborgioli.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/#primaryimage"},"image":{"@id":"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/pappardelle-molinoborgioli-video.jpg","datePublished":"2021-03-30T16:17:10+00:00","dateModified":"2021-09-01T10:19:12+00:00","description":"Pappardelle all'uovo una gustosa ricetta Naturalmente Molino Borgioli fatta con Semola fine","breadcrumb":{"@id":"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/#primaryimage","url":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/pappardelle-molinoborgioli-video.jpg","contentUrl":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/pappardelle-molinoborgioli-video.jpg","width":1087,"height":1087},{"@type":"BreadcrumbList","@id":"https:\/\/www.molinoborgioli.it\/en\/ricette\/pappardelle-alluovo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.molinoborgioli.it\/en\/"},{"@type":"ListItem","position":2,"name":"Ricette","item":"https:\/\/www.molinoborgioli.it\/en\/ricette\/"},{"@type":"ListItem","position":3,"name":"Pappardelle all&#8217;uovo"}]},{"@type":"WebSite","@id":"https:\/\/www.molinoborgioli.it\/en\/#website","url":"https:\/\/www.molinoborgioli.it\/en\/","name":"Naturalmente Molino Borgioli","description":"","publisher":{"@id":"https:\/\/www.molinoborgioli.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.molinoborgioli.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.molinoborgioli.it\/en\/#organization","name":"Naturalmente Molino Borgioli","url":"https:\/\/www.molinoborgioli.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.molinoborgioli.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/cropped-cropped-cropped-logo-borgioli-2-1-110x66-1.png","contentUrl":"https:\/\/www.molinoborgioli.it\/mb\/wp-content\/uploads\/2021\/03\/cropped-cropped-cropped-logo-borgioli-2-1-110x66-1.png","width":110,"height":66,"caption":"Naturalmente Molino Borgioli"},"image":{"@id":"https:\/\/www.molinoborgioli.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/ricette\/612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/ricette"}],"about":[{"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/types\/ricette"}],"author":[{"embeddable":true,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/comments?post=612"}],"version-history":[{"count":0,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/ricette\/612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/media\/1743"}],"wp:attachment":[{"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/media?parent=612"}],"wp:term":[{"taxonomy":"ricette-category","embeddable":true,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/ricette-category?post=612"},{"taxonomy":"prodotto-category","embeddable":true,"href":"https:\/\/www.molinoborgioli.it\/en\/wp-json\/wp\/v2\/prodotto-category?post=612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}